{"id":20412,"date":"2022-07-18T14:31:39","date_gmt":"2022-07-18T14:31:39","guid":{"rendered":"https:\/\/farelliprofesional.com\/?post_type=product&#038;p=20412"},"modified":"2025-11-18T07:05:19","modified_gmt":"2025-11-18T07:05:19","slug":"shampoo-matizador","status":"publish","type":"product","link":"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/","title":{"rendered":"Shampoo Matizador"},"content":{"rendered":"<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><strong><span class=\"JsGRdQ\">\u00a0<\/span><span class=\"JsGRdQ\">MODO DE EMPLEO:<\/span><\/strong><span class=\"JsGRdQ\"> Lavar previamente el cabello y en una segunda aplicaci\u00f3n masajear el cabello poniendo especial atenci\u00f3n en las \u00e1reas donde se desea matizar o intensificar. Dejar actuar de 5 a 10 minutos o mas si es posible, exprimir para permitir penetre de forma mas efectiva el pigmento y enjuagar. Se puede usar tambi\u00e9n en seco. La frecuencia de uso depender\u00e1 del grado deseado de i<\/span><span class=\"JsGRdQ\">ntensificado y matizado. 2 o 3 veces a la semana para el mantenimiento de color.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><strong><span class=\"JsGRdQ\">\u00a0<\/span><\/strong><span class=\"JsGRdQ\"><strong>ACTIVOS:<\/strong> Pantenol, humectantes y pigmentos de alta tecnolog\u00eda.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><strong><span class=\"JsGRdQ\">\u00a0<\/span><\/strong><span class=\"JsGRdQ\"><strong>IMPORTANTE:<\/strong>\u00a0Se recomienda usar guantes para el manejo del Shampoo. Evitar el contacto de los ojos. PH 5.5 a 6.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Ayudan a mantener el color cosm\u00e9tico en buen estado prologando su vida \u00fatil. Realza su belleza intensidad y brillo. Ideal para trabajos de color dejando un cabello hermoso.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">El shampoo matizador <\/span><span class=\"JsGRdQ\">violeta<\/span><span class=\"JsGRdQ\"> sirve para neutralizar los visos amarillos y naranjas del cabello.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">El shampoo <\/span><span class=\"JsGRdQ\">negro<\/span><span class=\"JsGRdQ\"> ideal para dar profundidad tonos oscuros o para platinar y cenizar el cabello en alturas superiores a 8.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\">\n","protected":false},"featured_media":20933,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[103,98,105],"product_tag":[],"class_list":{"0":"post-20412","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-matizadores","7":"product_cat-salon","8":"product_cat-shampoo","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ayudan a mantener el color cosm\u00e9tico en buen estado prologando su vida \u00fatil. Realza su belleza intensidad y brillo. Ideal para trabajos de color dejando un cabello hermoso. El shampoo matizador violeta sirve para neutralizar los visos amarillos y naranjas del cabello. El shampoo negro ideal para dar profundidad tonos oscuros o para platinar y cenizar el cabello en alturas superiores a 8.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_MX\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Farelli Profesional - Productos para el cuidado del cabello\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Shampoo Matizador - Farelli Profesional\" \/>\n\t\t<meta property=\"og:description\" content=\"Ayudan a mantener el color cosm\u00e9tico en buen estado prologando su vida \u00fatil. Realza su belleza intensidad y brillo. Ideal para trabajos de color dejando un cabello hermoso. El shampoo matizador violeta sirve para neutralizar los visos amarillos y naranjas del cabello. El shampoo negro ideal para dar profundidad tonos oscuros o para platinar y cenizar el cabello en alturas superiores a 8.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-07-18T14:31:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-11-18T07:05:19+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Shampoo Matizador - Farelli Profesional\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ayudan a mantener el color cosm\u00e9tico en buen estado prologando su vida \u00fatil. Realza su belleza intensidad y brillo. Ideal para trabajos de color dejando un cabello hermoso. El shampoo matizador violeta sirve para neutralizar los visos amarillos y naranjas del cabello. El shampoo negro ideal para dar profundidad tonos oscuros o para platinar y cenizar el cabello en alturas superiores a 8.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/producto\\\/shampoo-matizador\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/farelliprofesional.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/farelliprofesional.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/productos\\\/#listItem\",\"name\":\"Productos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/productos\\\/#listItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/productos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/categoria-producto\\\/salon\\\/#listItem\",\"name\":\"Sal\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/farelliprofesional.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/categoria-producto\\\/salon\\\/#listItem\",\"position\":3,\"name\":\"Sal\\u00f3n\",\"item\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/categoria-producto\\\/salon\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/categoria-producto\\\/salon\\\/matizadores\\\/#listItem\",\"name\":\"Matizadores\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/productos\\\/#listItem\",\"name\":\"Productos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/categoria-producto\\\/salon\\\/matizadores\\\/#listItem\",\"position\":4,\"name\":\"Matizadores\",\"item\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/categoria-producto\\\/salon\\\/matizadores\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/producto\\\/shampoo-matizador\\\/#listItem\",\"name\":\"Shampoo Matizador\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/categoria-producto\\\/salon\\\/#listItem\",\"name\":\"Sal\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/producto\\\/shampoo-matizador\\\/#listItem\",\"position\":5,\"name\":\"Shampoo Matizador\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/categoria-producto\\\/salon\\\/matizadores\\\/#listItem\",\"name\":\"Matizadores\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/producto\\\/shampoo-matizador\\\/#itempage\",\"url\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/producto\\\/shampoo-matizador\\\/\",\"name\":\"Shampoo Matizador - Farelli Profesional\",\"description\":\"Ayudan a mantener el color cosm\\u00e9tico en buen estado prologando su vida \\u00fatil. Realza su belleza intensidad y brillo. Ideal para trabajos de color dejando un cabello hermoso. El shampoo matizador violeta sirve para neutralizar los visos amarillos y naranjas del cabello. El shampoo negro ideal para dar profundidad tonos oscuros o para platinar y cenizar el cabello en alturas superiores a 8.\",\"inLanguage\":\"es-MX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/producto\\\/shampoo-matizador\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/farelliprofesional.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/17A.png\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/producto\\\/shampoo-matizador\\\/#mainImage\",\"width\":500,\"height\":500},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/producto\\\/shampoo-matizador\\\/#mainImage\"},\"datePublished\":\"2022-07-18T14:31:39+00:00\",\"dateModified\":\"2025-11-18T07:05:19+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/#organization\",\"name\":\"Farelli Profesional\",\"description\":\"Productos para el cuidado del cabello\",\"url\":\"https:\\\/\\\/farelliprofesional.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/farelliprofesional.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/LOGO-AMARILLO.png\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/producto\\\/shampoo-matizador\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/index.php\\\/producto\\\/shampoo-matizador\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/#website\",\"url\":\"https:\\\/\\\/farelliprofesional.com\\\/\",\"name\":\"Farelli Profesional\",\"description\":\"Productos para el cuidado del cabello\",\"inLanguage\":\"es-MX\",\"publisher\":{\"@id\":\"https:\\\/\\\/farelliprofesional.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Shampoo Matizador - Farelli Profesional","description":"Ayudan a mantener el color cosm\u00e9tico en buen estado prologando su vida \u00fatil. Realza su belleza intensidad y brillo. Ideal para trabajos de color dejando un cabello hermoso. El shampoo matizador violeta sirve para neutralizar los visos amarillos y naranjas del cabello. El shampoo negro ideal para dar profundidad tonos oscuros o para platinar y cenizar el cabello en alturas superiores a 8.","canonical_url":"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/farelliprofesional.com#listItem","position":1,"name":"Home","item":"https:\/\/farelliprofesional.com","nextItem":{"@type":"ListItem","@id":"https:\/\/farelliprofesional.com\/index.php\/productos\/#listItem","name":"Productos"}},{"@type":"ListItem","@id":"https:\/\/farelliprofesional.com\/index.php\/productos\/#listItem","position":2,"name":"Productos","item":"https:\/\/farelliprofesional.com\/index.php\/productos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/farelliprofesional.com\/index.php\/categoria-producto\/salon\/#listItem","name":"Sal\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/farelliprofesional.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/farelliprofesional.com\/index.php\/categoria-producto\/salon\/#listItem","position":3,"name":"Sal\u00f3n","item":"https:\/\/farelliprofesional.com\/index.php\/categoria-producto\/salon\/","nextItem":{"@type":"ListItem","@id":"https:\/\/farelliprofesional.com\/index.php\/categoria-producto\/salon\/matizadores\/#listItem","name":"Matizadores"},"previousItem":{"@type":"ListItem","@id":"https:\/\/farelliprofesional.com\/index.php\/productos\/#listItem","name":"Productos"}},{"@type":"ListItem","@id":"https:\/\/farelliprofesional.com\/index.php\/categoria-producto\/salon\/matizadores\/#listItem","position":4,"name":"Matizadores","item":"https:\/\/farelliprofesional.com\/index.php\/categoria-producto\/salon\/matizadores\/","nextItem":{"@type":"ListItem","@id":"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/#listItem","name":"Shampoo Matizador"},"previousItem":{"@type":"ListItem","@id":"https:\/\/farelliprofesional.com\/index.php\/categoria-producto\/salon\/#listItem","name":"Sal\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/#listItem","position":5,"name":"Shampoo Matizador","previousItem":{"@type":"ListItem","@id":"https:\/\/farelliprofesional.com\/index.php\/categoria-producto\/salon\/matizadores\/#listItem","name":"Matizadores"}}]},{"@type":"ItemPage","@id":"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/#itempage","url":"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/","name":"Shampoo Matizador - Farelli Profesional","description":"Ayudan a mantener el color cosm\u00e9tico en buen estado prologando su vida \u00fatil. Realza su belleza intensidad y brillo. Ideal para trabajos de color dejando un cabello hermoso. El shampoo matizador violeta sirve para neutralizar los visos amarillos y naranjas del cabello. El shampoo negro ideal para dar profundidad tonos oscuros o para platinar y cenizar el cabello en alturas superiores a 8.","inLanguage":"es-MX","isPartOf":{"@id":"https:\/\/farelliprofesional.com\/#website"},"breadcrumb":{"@id":"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/farelliprofesional.com\/wp-content\/uploads\/2022\/07\/17A.png","@id":"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/#mainImage","width":500,"height":500},"primaryImageOfPage":{"@id":"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/#mainImage"},"datePublished":"2022-07-18T14:31:39+00:00","dateModified":"2025-11-18T07:05:19+00:00"},{"@type":"Organization","@id":"https:\/\/farelliprofesional.com\/#organization","name":"Farelli Profesional","description":"Productos para el cuidado del cabello","url":"https:\/\/farelliprofesional.com\/","logo":{"@type":"ImageObject","url":"https:\/\/farelliprofesional.com\/wp-content\/uploads\/2023\/02\/LOGO-AMARILLO.png","@id":"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/farelliprofesional.com\/#website","url":"https:\/\/farelliprofesional.com\/","name":"Farelli Profesional","description":"Productos para el cuidado del cabello","inLanguage":"es-MX","publisher":{"@id":"https:\/\/farelliprofesional.com\/#organization"}}]},"og:locale":"es_MX","og:site_name":"Farelli Profesional - Productos para el cuidado del cabello","og:type":"article","og:title":"Shampoo Matizador - Farelli Profesional","og:description":"Ayudan a mantener el color cosm\u00e9tico en buen estado prologando su vida \u00fatil. Realza su belleza intensidad y brillo. Ideal para trabajos de color dejando un cabello hermoso. El shampoo matizador violeta sirve para neutralizar los visos amarillos y naranjas del cabello. El shampoo negro ideal para dar profundidad tonos oscuros o para platinar y cenizar el cabello en alturas superiores a 8.","og:url":"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/","article:published_time":"2022-07-18T14:31:39+00:00","article:modified_time":"2025-11-18T07:05:19+00:00","twitter:card":"summary","twitter:title":"Shampoo Matizador - Farelli Profesional","twitter:description":"Ayudan a mantener el color cosm\u00e9tico en buen estado prologando su vida \u00fatil. Realza su belleza intensidad y brillo. Ideal para trabajos de color dejando un cabello hermoso. El shampoo matizador violeta sirve para neutralizar los visos amarillos y naranjas del cabello. El shampoo negro ideal para dar profundidad tonos oscuros o para platinar y cenizar el cabello en alturas superiores a 8."},"aioseo_meta_data":{"post_id":"20412","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"aioseo-web-page-63edaa00aaeef","slug":"web-page","graphName":"WebPage","label":"Web Page","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-07-18 14:31:39","updated":"2025-11-18 07:06:36","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/farelliprofesional.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/farelliprofesional.com\/index.php\/productos\/\" title=\"Productos\">Productos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/farelliprofesional.com\/index.php\/categoria-producto\/salon\/\" title=\"Sal\u00f3n\">Sal\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/farelliprofesional.com\/index.php\/categoria-producto\/salon\/matizadores\/\" title=\"Matizadores\">Matizadores<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tShampoo Matizador\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/farelliprofesional.com"},{"label":"Productos","link":"https:\/\/farelliprofesional.com\/index.php\/productos\/"},{"label":"Sal\u00f3n","link":"https:\/\/farelliprofesional.com\/index.php\/categoria-producto\/salon\/"},{"label":"Matizadores","link":"https:\/\/farelliprofesional.com\/index.php\/categoria-producto\/salon\/matizadores\/"},{"label":"Shampoo Matizador","link":"https:\/\/farelliprofesional.com\/index.php\/producto\/shampoo-matizador\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/farelliprofesional.com\/index.php\/wp-json\/wp\/v2\/product\/20412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/farelliprofesional.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/farelliprofesional.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/farelliprofesional.com\/index.php\/wp-json\/wp\/v2\/comments?post=20412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/farelliprofesional.com\/index.php\/wp-json\/wp\/v2\/media\/20933"}],"wp:attachment":[{"href":"https:\/\/farelliprofesional.com\/index.php\/wp-json\/wp\/v2\/media?parent=20412"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/farelliprofesional.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=20412"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/farelliprofesional.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=20412"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/farelliprofesional.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=20412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}